{"id":13785,"date":"2023-05-11T23:38:52","date_gmt":"2023-05-11T21:38:52","guid":{"rendered":"https:\/\/lapasion.es\/politica-cookies\/"},"modified":"2023-05-19T11:58:42","modified_gmt":"2023-05-19T09:58:42","slug":"politique-d-utilisation-de-cookies2","status":"publish","type":"page","link":"https:\/\/lapasion.es\/fr\/politique-d-utilisation-de-cookies2\/","title":{"rendered":"Politique de cookies"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-1e1e5acc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Cette politique de cookies a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le 18 juin 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00c9conomique Europ\u00e9en et de la Suisse.<\/i><br><\/p><h2>1. Introduction<\/h2><p>Notre site web, <a href=\"https:\/\/lapasion.es\/fr\/\">https:\/\/lapasion.es\/fr\/<\/a> (ci-apr\u00e8s\u00a0: \u00ab\u00a0le site web\u00a0\u00bb) utilise des cookies et autres technologies li\u00e9es (par simplification, toutes ces technologies sont d\u00e9sign\u00e9es par le terme \u00ab\u00a0cookies\u00a0\u00bb). Des cookies sont \u00e9galement plac\u00e9s par des tierces parties que nous avons engag\u00e9es. Dans le document ci-dessous, nous vous informons de l\u2019utilisation des cookies sur notre site web.<\/p><h2>2. Que sont les cookies\u00a0?<\/h2><p>Un cookie est un petit fichier simple envoy\u00e9 avec les pages de ce site web et stock\u00e9 par votre navigateur sur le disque dur de votre ordinateur ou d\u2019un autre appareil. Les informations qui y sont stock\u00e9es peuvent \u00eatre renvoy\u00e9es \u00e0 nos serveurs ou aux serveurs des tierces parties concern\u00e9es lors d\u2019une visite ult\u00e9rieure.<\/p><h2>3. Que sont les scripts\u00a0?<\/h2><p>Un script est un \u00e9l\u00e9ment de code utilis\u00e9 pour que notre site web fonctionne correctement et de mani\u00e8re interactive. Ce code est ex\u00e9cut\u00e9 sur notre serveur ou sur votre appareil.<\/p><h2>4. Qu\u2019est-ce qu\u2019une balise invisible\u00a0?<\/h2><p>Une balise invisible (ou balise web) est un petit morceau de texte ou d\u2019image invisible sur un site web, utilis\u00e9 pour suivre le trafic sur un site web. Pour ce faire, diverses donn\u00e9es vous concernant sont stock\u00e9es \u00e0 l\u2019aide de balises invisibles.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies techniques ou fonctionnels<\/p><p>Certains cookies assurent le fonctionnement correct de certaines parties du site web et la prise en compte de vos pr\u00e9f\u00e9rences en tant qu\u2019internaute. En pla\u00e7ant des cookies fonctionnels, nous vous facilitons la visite de notre site web. Ainsi, vous n\u2019avez pas besoin de saisir \u00e0 plusieurs reprises les m\u00eames informations lors de la visite de notre site web et, par exemple, les \u00e9l\u00e9ments restent dans votre panier jusqu\u2019\u00e0 votre paiement. Nous pouvons d\u00e9poser ces cookies sans votre consentement.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies statistiques<\/p><p>Nous utilisons des cookies statistiques afin d\u2019optimiser l\u2019exp\u00e9rience des internautes sur notre site web. Avec ces cookies statistiques, nous obtenons des informations sur l\u2019utilisation de notre site web.&nbsp;Nous demandons votre permission pour placer des cookies statistiques.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de marketing\/suivi<\/p><p>Les cookies de marketing\/suivi sont des cookies ou toute autre forme de stockage local, utilis\u00e9s pour cr\u00e9er des profils d\u2019utilisateurs afin d\u2019afficher de la publicit\u00e9 ou de suivre l\u2019utilisateur sur ce site web ou sur plusieurs sites web dans des finalit\u00e9s marketing similaires.<\/p><h2>6. Cookies plac\u00e9s<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Active Campaign<\/h3>\n\t\t<p>Marketing, Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_active-campaign\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service active-campaign<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_active-campaign\" class=\"cmplz-accept-service \" data-service=\"active-campaign\" data-category=\"marketing\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Active Campaign pour marketing automation (automated email marketing). <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/active-campaign\/\">En savoir plus sur Active Campaign<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.activecampaign.com\/legal\/privacy-policy\">d\u00e9claration de confidentialit\u00e9 Active Campaign<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/active-campaign\/prism_\/\">prism_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store and track interaction<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/active-campaign\/ac_enable_tracking\/\">ac_enable_tracking<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences de consentement aux cookies<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service \" data-service=\"google-recaptcha\" data-category=\"marketing\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google reCAPTCHA pour le blocage des ind\u00e9sirables. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">En savoir plus sur Google reCAPTCHA<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google reCAPTCHA<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Filtrer les requ\u00eates des robots<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Filtrer les requ\u00eates des robots<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Filtrer les requ\u00eates des robots<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service \" data-service=\"google-fonts\" data-category=\"marketing\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Fonts pour l\u2019affichage des polices web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">En savoir plus sur Google Fonts<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">aucune<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Demander l\u2019adresse IP de l\u2019utilisateur<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Fonctionnel, Functional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service \" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WordPress pour le d\u00e9veloppement du site web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">En savoir plus sur WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_PREFERENCES_USER_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les informations du navigateur<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_lang\/\">wp_lang<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les r\u00e9glages de langue<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Read if cookies can be placed<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Advanced Custom Fields<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_advanced-custom-fields\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service advanced-custom-fields<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_advanced-custom-fields\" class=\"cmplz-accept-service \" data-service=\"advanced-custom-fields\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">acf<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">aucune<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Fournir des fonctions sur toutes les pages<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Tawk<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_tawk\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service tawk<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_tawk\" class=\"cmplz-accept-service \" data-service=\"tawk\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Tawk pour l\u2019assistance par discussion instantan\u00e9e. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/tawk\/\">En savoir plus sur Tawk<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.tawk.to\/privacy-policy\/\">d\u00e9claration de confidentialit\u00e9 Tawk<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/tawk\/twk_\/\">twk_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WooCommerce<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_woocommerce\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service woocommerce<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_woocommerce\" class=\"cmplz-accept-service \" data-service=\"woocommerce\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WooCommerce pour la gestion de boutique en ligne. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/woocommerce\/\">En savoir plus sur WooCommerce<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wc_cart_hash_\/\">wc_cart_hash_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store items in shopping cart<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/woocommerce_items_in_cart\/\">woocommerce_items_in_cart<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store items in shopping cart<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/woocommerce_cart_hash\/\">woocommerce_cart_hash<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store items in shopping cart<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/woocommerce\/wp_woocommerce_session_-2\/\">wp_woocommerce_session_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store performed actions on the website<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Tag Manager for WordPress<\/h3>\n\t\t<p>Statistiques<\/p>\n\t\t<label for=\"cmplz_service_google-tag-manager-for-wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-tag-manager-for-wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-tag-manager-for-wordpress\" class=\"cmplz-accept-service \" data-service=\"google-tag-manager-for-wordpress\" data-category=\"statistics\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Tag Manager for WordPress pour les statistiques du site web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-tag-manager-for-wordpress\/\">En savoir plus sur Google Tag Manager for WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-tag-manager-for-wordpress\/gtm4wp_orderid_tracked\/\">gtm4wp_orderid_tracked<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 an<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker et suivre les interactions<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service \" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Complianz pour la gestion du consentement aux cookies. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\">En savoir plus sur Complianz<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.&nbsp;Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">d\u00e9claration de confidentialit\u00e9 Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_consented_services\/\">cmplz_consented_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_policy_id\/\">cmplz_policy_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store accepted cookie policy ID<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_marketing\/\">cmplz_marketing<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_statistics\/\">cmplz_statistics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_preferences\/\">cmplz_preferences<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_banner-status\/\">cmplz_banner-status<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store if the cookie banner has been dismissed<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sourcebuster JS<\/h3>\n\t\t<p>Statistics<\/p>\n\t\t<label for=\"cmplz_service_sourcebuster-js\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sourcebuster-js<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sourcebuster-js\" class=\"cmplz-accept-service \" data-service=\"sourcebuster-js\" data-category=\"statistics\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Sourcebuster JS pour le suivi des visiteurs. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/sourcebuster-js\/\">En savoir plus sur Sourcebuster JS<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistics<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_migrations\/\">sbjs_migrations<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first_add\/\">sbjs_first_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_current\/\">sbjs_current<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store browser details<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first\/\">sbjs_first<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_session\/\">sbjs_session<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service \" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WPML pour locale management. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpml\/\">En savoir plus sur WPML<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpml\/wp-wpml_current_language\/\">wp-wpml_current_language<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store language settings<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistiques, Statistics<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service \" data-service=\"google-analytics\" data-category=\"statistics\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Analytics pour les statistiques du site web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">En savoir plus sur Google Analytics<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google Analytics<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gid\/\">_gid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 jour<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Compter et suivre les pages visit\u00e9es<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_dc_gtm_ua\/\">_dc_gtm_UA-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 minute<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker le nombre de requ\u00eates du service<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistics<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_ga_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store and count pageviews<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Store and count pageviews<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Divers<\/h3>\n\t\t<p>Statistics<\/p>\n\t\t<label for=\"cmplz_service_divers\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service divers<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_divers\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"divers\" data-category=\"statistics\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Le partage des donn\u00e9es est en cours d\u2019enqu\u00eate<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/df\/\">df-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">08520778-a8f0-46fe-8ed3-b4e69cc161bd.data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">real-queue-restore-jobs-b39b4274fdcc114292e64307bbc5b5dc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">uagSvgConfirmation<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_10<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">spectraCopyPasteStyles<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">b992651d-fc8a-4f0d-8948-d1255bb2ab0e.data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">uagSettingState<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_dc_gtm_UA-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_cookie_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-autosave-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">marketplace_redesign_2023_last_shown_date<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_hjSessionUser_2868906<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">headingsMap_selectedTab<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">friends_with_mate<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_3<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_clck<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_clsk<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wc_fragments_e281f3d9d4061a74f246c1b0aee73ee7<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wc_cart_created<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lastExternalReferrer<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lastExternalReferrerTime<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_cltk<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_fbp<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_fbc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">multiFbc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">topicsLastReferenceTime<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">adobeCleanFontAdded<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_gcl_ls<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_gcl_au<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">__kla_viewed<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">__kl_key<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">$referrer<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">$last_referrer<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">__kla_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_kx<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">awca_ga4_session_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_915<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">loglevel<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">klaviyoOnsite<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wc_iam_settings<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">storeApiCartData<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">gla-can-onboarding-setup-ces-prompt-open<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">klaviyoPagesVisitCountV2<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">distributor-cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistics<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sbjs_current_add\/\">sbjs_current_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sbjs_udata\/\">sbjs_udata<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentement<\/h2><p>Lorsque vous visitez notre site web pour la premi\u00e8re fois, nous vous montrerons une fen\u00eatre contextuelle avec une explication sur les cookies. D\u00e8s que vous cliquez sur \u00ab\u00a0Guardar preferencias\u00a0\u00bb vous nous autorisez \u00e0 utiliser les cat\u00e9gories de cookies et d\u2019extensions que vous avez s\u00e9lectionn\u00e9s dans la fen\u00eatre contextuelle, comme d\u00e9crit dans la pr\u00e9sente politique de cookies. Vous pouvez d\u00e9sactiver l\u2019utilisation des cookies via votre navigateur, mais veuillez noter que notre site web pourrait ne plus fonctionner correctement.<\/p><p class=\"cmplz-subtitle\">7.1 G\u00e9rez vos r\u00e9glages de consentement<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Vous avez charg\u00e9 la politique de cookies sans le support de javascript.&nbsp;Sur AMP, vous pouvez utiliser l\u2019onglet de gestion du consentement en bas de la page.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activer\/d\u00e9sactiver et supprimer les cookies<\/h2><p>Vous pouvez utiliser votre navigateur internet pour supprimer automatiquement ou manuellement les cookies. Vous pouvez \u00e9galement sp\u00e9cifier que certains cookies ne peuvent pas \u00eatre plac\u00e9s. Une autre option consiste \u00e0 modifier les r\u00e9glages de votre navigateur Internet afin que vous receviez un message \u00e0 chaque fois qu\u2019un cookie est plac\u00e9. Pour plus d\u2019informations sur ces options, reportez-vous aux instructions de la section Aide de votre navigateur.<\/p><p>Veuillez noter que notre site web peut ne pas marcher correctement si tous les cookies sont d\u00e9sactiv\u00e9s. Si vous supprimez les cookies dans votre navigateur, ils seront de nouveau plac\u00e9s apr\u00e8s votre consentement lorsque vous revisiterez notre site web.<\/p><h2>9. Vos droits concernant les donn\u00e9es personnelles<\/h2><p>Vous avez les droits suivants concernant vos donn\u00e9es personnelles\u00a0:<\/p><ul>\n                    <li>Vous avez le droit de savoir pourquoi vos donn\u00e9es personnelles sont n\u00e9cessaires, ce qui leur arrivera et combien de temps elles seront conserv\u00e9es.<\/li>\n                    <li>Droit d\u2019acc\u00e8s\u00a0: vous avez le droit d\u2019acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous connaissons.<\/li>\n                    <li>Droit de rectification\u00a0: vous avez le droit \u00e0 tout moment de compl\u00e9ter, corriger, faire supprimer ou bloquer vos donn\u00e9es personnelles.<\/li>\n                    <li>Si vous nous donnez votre consentement pour le traitement de vos donn\u00e9es, vous avez le droit de r\u00e9voquer ce consentement et de faire supprimer vos donn\u00e9es personnelles.<\/li>\n                    <li>Droit de transf\u00e9rer vos donn\u00e9es\u00a0: vous avez le droit de demander toutes vos donn\u00e9es personnelles au responsable du traitement et de les transf\u00e9rer dans leur int\u00e9gralit\u00e9 \u00e0 un autre responsable du traitement.<\/li>\n                    <li>Droit d\u2019opposition\u00a0: vous pouvez vous opposer au traitement de vos donn\u00e9es. Nous obtemp\u00e9rerons, \u00e0 moins que certaines raisons ne justifient ce traitement.<\/li>\n                <\/ul><p>Pour exercer ces droits, veuillez nous contacter. Veuillez vous r\u00e9f\u00e9rer aux coordonn\u00e9es au bas de cette politique de cookies. Si vous avez une plainte concernant la fa\u00e7on dont nous traitons vos donn\u00e9es, nous aimerions en \u00eatre inform\u00e9s, mais vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l\u2019autorit\u00e9 de contr\u00f4le (l\u2019autorit\u00e9 charg\u00e9e de la protection des donn\u00e9es).<\/p><h2>10. Coordonn\u00e9es<\/h2><p>Pour des questions et\/ou des commentaires sur notre politique de cookies et cette d\u00e9claration, veuillez nous contacter en utilisant les coordonn\u00e9es suivantes\u00a0:<\/p><p><span class=\"cmplz-contact-organisation\">LAPASION INTERNACIONAL, SA<\/span><br>\n                      <span class=\"cmplz-contact-address\">POL. IND. MALPICA \u2013 C\/F OESTE PARCELA 47 , 50016 ZARAGOZA (ZARAGOZA) <\/span><br>\n                      <span class=\"cmplz-contact-country\">Espagne<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Site web\u00a0: <a href=\"https:\/\/lapasion.es\/fr\/\">https:\/\/lapasion.es\/fr\/<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">E-mail\u00a0: <span class=\"cmplz-obfuscate\">&#109;&#097;&#114;&#107;&#101;&#116;ing@<span class=\"cmplz-fmail-domain\">&#101;x.c&#111;m<\/span>la&#112;&#097;si&#111;n.&#101;&#115;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Num\u00e9ro de t\u00e9l\u00e9phone : 976570892<\/span><\/p><p>Cette politique de cookies a \u00e9t\u00e9 synchronis\u00e9e avec <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> le 18 juin 2024.<\/p><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-13785","1":"page","2":"type-page","3":"status-publish","5":"entry"},"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gur_featured_image":false,"gur_blog_thumbnail":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"cvaliente","author_link":"https:\/\/lapasion.es\/fr\/author\/cvaliente\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/pages\/13785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/comments?post=13785"}],"version-history":[{"count":0,"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/pages\/13785\/revisions"}],"wp:attachment":[{"href":"https:\/\/lapasion.es\/fr\/wp-json\/wp\/v2\/media?parent=13785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}